{"id":811,"date":"2022-12-21T11:59:49","date_gmt":"2022-12-21T11:59:49","guid":{"rendered":"https:\/\/turkuyilmazkaya-psychotherapie.com\/?page_id=811"},"modified":"2022-12-29T08:42:26","modified_gmt":"2022-12-29T08:42:26","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"811\" class=\"elementor elementor-811\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b3adaab e-container--row e-container\" data-id=\"5b3adaab\" data-element_type=\"container\" id=\"wrapperBox\">\t\t<div class=\"elementor-element elementor-element-795784e3 e-container--column e-container\" data-id=\"795784e3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\t\t<div class=\"elementor-element elementor-element-aab1483 e-container--column e-container\" data-id=\"aab1483\" data-element_type=\"container\">\t\t\t\t<div class=\"elementor-element elementor-element-eba74cf elementor-widget elementor-widget-heading\" data-id=\"eba74cf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Datenschutz<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67d7147 elementor-widget elementor-widget-text-editor\" data-id=\"67d7147\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h2>Einleitung und \u00dcberblick<\/h2><p>Wir haben diese Datenschutzerkl\u00e4rung (Fassung 26.11.2021-121888354) verfasst, um Ihnen gem\u00e4\u00df der Vorgaben der\u00a0<a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/DE\/ALL\/?uri=celex%3A32016R0679&amp;tid=121888354\" target=\"_blank\" rel=\"noreferrer noopener\">Datenschutz-Grundverordnung (EU) 2016\/679<\/a>\u00a0und anwendbaren nationalen Gesetzen zu erkl\u00e4ren, welche personenbezogenen Daten (kurz Daten) wir als Verantwortliche \u2013 und die von uns beauftragten Auftragsverarbeiter (z. B. Provider) \u2013 verarbeiten, zuk\u00fcnftig verarbeiten werden und welche rechtm\u00e4\u00dfigen M\u00f6glichkeiten Sie haben. Die verwendeten Begriffe sind geschlechtsneutral zu verstehen.<br \/>Kurz gesagt: Wir informieren Sie umfassend \u00fcber Daten, die wir \u00fcber Sie verarbeiten.<\/p><p>Datenschutzerkl\u00e4rungen klingen f\u00fcr gew\u00f6hnlich sehr technisch und verwenden juristische Fachbegriffe. Diese Datenschutzerkl\u00e4rung soll Ihnen hingegen die wichtigsten Dinge so einfach und transparent wie m\u00f6glich beschreiben. Soweit es der Transparenz f\u00f6rderlich ist, werden technische Begriffe leserfreundlich erkl\u00e4rt, Links zu weiterf\u00fchrenden Informationen geboten und Grafiken zum Einsatz gebracht. Wir informieren damit in klarer und einfacher Sprache, dass wir im Rahmen unserer Gesch\u00e4ftst\u00e4tigkeiten nur dann personenbezogene Daten verarbeiten, wenn eine entsprechende gesetzliche Grundlage gegeben ist. Das ist sicher nicht m\u00f6glich, wenn man m\u00f6glichst knappe, unklare und juristisch-technische Erkl\u00e4rungen abgibt, so wie sie im Internet oft Standard sind, wenn es um Datenschutz geht. Ich hoffe, Sie finden die folgenden Erl\u00e4uterungen interessant und informativ und vielleicht ist die eine oder andere Information dabei, die Sie noch nicht kannten.<br \/>Wenn trotzdem Fragen bleiben, m\u00f6chten wir Sie bitten, sich an die unten bzw. im Impressum genannte verantwortliche Stelle zu wenden, den vorhandenen Links zu folgen und sich weitere Informationen auf Drittseiten anzusehen. Unsere Kontaktdaten finden Sie selbstverst\u00e4ndlich auch im Impressum.<\/p><p>\u00a0<\/p><h2>Anwendungsbereich<\/h2><p>Diese Datenschutzerkl\u00e4rung gilt f\u00fcr alle von uns im Unternehmen verarbeiteten personenbezogenen Daten und f\u00fcr alle personenbezogenen Daten, die von uns beauftragte Firmen (Auftragsverarbeiter) verarbeiten. Mit personenbezogenen Daten meinen wir Informationen im Sinne des Art. 4 Nr. 1 DSGVO wie zum Beispiel Name, E-Mail-Adresse und postalische Anschrift einer Person. Die Verarbeitung personenbezogener Daten sorgt daf\u00fcr, dass wir unsere Dienstleistungen und Produkte anbieten und abrechnen k\u00f6nnen, sei es online oder offline. Der Anwendungsbereich dieser Datenschutzerkl\u00e4rung umfasst:<\/p><ul><li><p>alle Onlineauftritte (Websites, Onlineshops), die wir betreiben<\/p><\/li><li><p>Social Media Auftritte und E-Mail-Kommunikation<\/p><\/li><li><p>mobile Apps f\u00fcr Smartphones und andere Ger\u00e4te<\/p><\/li><\/ul><p>Kurz gesagt: Die Datenschutzerkl\u00e4rung gilt f\u00fcr alle Bereiche, in denen personenbezogene Daten im Unternehmen \u00fcber die genannten Kan\u00e4le strukturiert verarbeitet werden. Sollten wir au\u00dferhalb dieser Kan\u00e4le mit Ihnen in Rechtsbeziehungen eintreten, werden wir Sie gegebenenfalls gesondert informieren.<\/p><p>\u00a0<\/p><h2>Rechtsgrundlagen<\/h2><p>In der folgenden Datenschutzerkl\u00e4rung geben wir Ihnen transparente Informationen zu den rechtlichen Grunds\u00e4tzen und Vorschriften, also den Rechtsgrundlagen der Datenschutz-Grundverordnung, die uns erm\u00f6glichen, personenbezogene Daten zu verarbeiten.<br \/>Was das EU-Recht betrifft, beziehen wir uns auf die VERORDNUNG (EU) 2016\/679 DES EUROP\u00c4ISCHEN PARLAMENTS UND DES RATES vom 27. April 2016. Diese Datenschutz-Grundverordnung der EU k\u00f6nnen Sie selbstverst\u00e4ndlich online auf EUR-Lex, dem Zugang zum EU-Recht, unter\u00a0<a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/DE\/ALL\/?uri=celex%3A32016R0679&amp;tid=121888354\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/eur-lex.europa.eu\/legal-content\/DE\/TXT\/?uri=celex%3A32016R0679<\/a>\u00a0nachlesen.<\/p><p>Wir verarbeiten Ihre Daten nur, wenn mindestens eine der folgenden Bedingungen zutrifft:<\/p><ol><li><p>Einwilligung (Artikel 6 Absatz 1 lit. a DSGVO): Sie haben uns Ihre Einwilligung gegeben, Daten zu einem bestimmten Zweck zu verarbeiten. Ein Beispiel w\u00e4re die Speicherung Ihrer eingegebenen Daten eines Kontaktformulars.<\/p><\/li><li><p>Vertrag (Artikel 6 Absatz 1 lit. b DSGVO): Um einen Vertrag oder vorvertragliche Verpflichtungen mit Ihnen zu erf\u00fcllen, verarbeiten wir Ihre Daten. Wenn wir zum Beispiel einen Kaufvertrag mit Ihnen abschlie\u00dfen, ben\u00f6tigen wir vorab personenbezogene Informationen.<\/p><\/li><li><p>Rechtliche Verpflichtung (Artikel 6 Absatz 1 lit. c DSGVO): Wenn wir einer rechtlichen Verpflichtung unterliegen, verarbeiten wir Ihre Daten. Zum Beispiel sind wir gesetzlich verpflichtet Rechnungen f\u00fcr die Buchhaltung aufzuheben. Diese enthalten in der Regel personenbezogene Daten.<\/p><\/li><li><p>Berechtigte Interessen (Artikel 6 Absatz 1 lit. f DSGVO): Im Falle berechtigter Interessen, die Ihre Grundrechte nicht einschr\u00e4nken, behalten wir uns die Verarbeitung personenbezogener Daten vor. Wir m\u00fcssen zum Beispiel gewisse Daten verarbeiten, um unsere Website sicher und wirtschaftlich effizient betreiben zu k\u00f6nnen. Diese Verarbeitung ist somit ein berechtigtes Interesse.<\/p><\/li><\/ol><p>Weitere Bedingungen wie die Wahrnehmung von Aufnahmen im \u00f6ffentlichen Interesse und Aus\u00fcbung \u00f6ffentlicher Gewalt sowie dem Schutz lebenswichtiger Interessen treten bei uns in der Regel nicht auf. Soweit eine solche Rechtsgrundlage doch einschl\u00e4gig sein sollte, wird diese an der entsprechenden Stelle ausgewiesen.<\/p><p>Zus\u00e4tzlich zu der EU-Verordnung gelten auch noch nationale Gesetze:<\/p><ul><li><p>In \u00d6sterreich ist dies das Bundesgesetz zum Schutz nat\u00fcrlicher Personen bei der Verarbeitung personenbezogener Daten (Datenschutzgesetz), kurz DSG.<\/p><\/li><li><p>In Deutschland gilt das Bundesdatenschutzgesetz, kurz BDSG.<\/p><\/li><\/ul><p>Sofern weitere regionale oder nationale Gesetze zur Anwendung kommen, informieren wir Sie in den folgenden Abschnitten dar\u00fcber.<\/p><p>\u00a0<\/p><h2>Kontaktdaten des Verantwortlichen<\/h2><p>Sollten Sie Fragen zum Datenschutz haben, finden Sie nachfolgend die Kontaktdaten der verantwortlichen Person bzw. Stelle:<br \/>T\u00fcrk\u00fc\u00a0<span style=\"color: var( --e-global-color-accent ); text-align: var(--text-align); background-color: var( --e-global-color-1e292e7 );\">Y\u0131lmazkaya\u00a0<\/span><span style=\"color: var( --e-global-color-accent ); text-align: var(--text-align); background-color: var( --e-global-color-1e292e7 );\">W\u00e4hringerstra\u00dfe 47\/3, 1090 Wien<\/span><\/p><p>E-Mail: <a href=\"turkuyilmazkaya.psychotherapie@gmail.com\" target=\"_self\">turkuyilmazkaya.psychotherapie@gmail.com<\/a><br \/>Telefon: +43 660 956 5508<\/p><p>\u00a0<\/p><h2>Speicherdauer<\/h2><p>Dass wir personenbezogene Daten nur so lange speichern, wie es f\u00fcr die Bereitstellung unserer Dienstleistungen und Produkte unbedingt notwendig ist, gilt als generelles Kriterium bei uns. Das bedeutet, dass wir personenbezogene Daten l\u00f6schen, sobald der Grund f\u00fcr die Datenverarbeitung nicht mehr vorhanden ist. In einigen F\u00e4llen sind wir gesetzlich dazu verpflichtet, bestimmte Daten auch nach Wegfall des urspr\u00fcngliches Zwecks zu speichern, zum Beispiel zu Zwecken der Buchf\u00fchrung.<\/p><p>Sollten Sie die L\u00f6schung Ihrer Daten w\u00fcnschen oder die Einwilligung zur Datenverarbeitung widerrufen, werden die Daten so rasch wie m\u00f6glich und soweit keine Pflicht zur Speicherung besteht, gel\u00f6scht.<\/p><p>\u00dcber die konkrete Dauer der jeweiligen Datenverarbeitung informieren wir Sie weiter unten, sofern wir weitere Informationen dazu haben.<\/p><p>\u00a0<\/p><h2>Rechte laut Datenschutz-Grundverordnung<\/h2><p>Laut Artikel 13 DSGVO stehen Ihnen die folgenden Rechte zu, damit es zu einer fairen und transparenten Verarbeitung von Daten kommt:<\/p><ul><li><p>Sie haben laut Artikel 15 DSGVO ein Auskunftsrecht dar\u00fcber, ob wir Daten von Ihnen verarbeiten. Sollte das zutreffen, haben Sie Recht darauf eine Kopie der Daten zu erhalten und die folgenden Informationen zu erfahren:<\/p><ul><li><p>zu welchem Zweck wir die Verarbeitung durchf\u00fchren;<\/p><\/li><li><p>die Kategorien, also die Arten von Daten, die verarbeitet werden;<\/p><\/li><li><p>wer diese Daten erh\u00e4lt und wenn die Daten an Drittl\u00e4nder \u00fcbermittelt werden, wie die Sicherheit garantiert werden kann;<\/p><\/li><li><p>wie lange die Daten gespeichert werden;<\/p><\/li><li><p>das Bestehen des Rechts auf Berichtigung, L\u00f6schung oder Einschr\u00e4nkung der Verarbeitung und dem Widerspruchsrecht gegen die Verarbeitung;<\/p><\/li><li><p>dass Sie sich bei einer Aufsichtsbeh\u00f6rde beschweren k\u00f6nnen (Links zu diesen Beh\u00f6rden finden Sie weiter unten);<\/p><\/li><li><p>die Herkunft der Daten, wenn wir sie nicht bei Ihnen erhoben haben;<\/p><\/li><li><p>ob Profiling durchgef\u00fchrt wird, ob also Daten automatisch ausgewertet werden, um zu einem pers\u00f6nlichen Profil von Ihnen zu gelangen.<\/p><\/li><\/ul><\/li><li><p>Sie haben laut Artikel 16 DSGVO ein Recht auf Berichtigung der Daten, was bedeutet, dass wir Daten richtig stellen m\u00fcssen, falls Sie Fehler finden.<\/p><\/li><li><p>Sie haben laut Artikel 17 DSGVO das Recht auf L\u00f6schung (\u201eRecht auf Vergessenwerden\u201c), was konkret bedeutet, dass Sie die L\u00f6schung Ihrer Daten verlangen d\u00fcrfen.<\/p><\/li><li><p>Sie haben laut Artikel 18 DSGVO das Recht auf Einschr\u00e4nkung der Verarbeitung, was bedeutet, dass wir die Daten nur mehr speichern d\u00fcrfen aber nicht weiter verwenden.<\/p><\/li><li><p>Sie haben laut Artikel 19 DSGVO das Recht auf Daten\u00fcbertragbarkeit, was bedeutet, dass wir Ihnen auf Anfrage Ihre Daten in einem g\u00e4ngigen Format zur Verf\u00fcgung stellen.<\/p><\/li><li><p>Sie haben laut Artikel 21 DSGVO ein Widerspruchsrecht, welches nach Durchsetzung eine \u00c4nderung der Verarbeitung mit sich bringt.<\/p><ul><li><p>Wenn die Verarbeitung Ihrer Daten auf Artikel 6 Abs. 1 lit. e (\u00f6ffentliches Interesse, Aus\u00fcbung \u00f6ffentlicher Gewalt) oder Artikel 6 Abs. 1 lit. f (berechtigtes Interesse) basiert, k\u00f6nnen Sie gegen die Verarbeitung Widerspruch einlegen. Wir pr\u00fcfen danach so rasch wie m\u00f6glich, ob wir diesem Widerspruch rechtlich nachkommen k\u00f6nnen.<\/p><\/li><li><p>Werden Daten verwendet, um Direktwerbung zu betreiben, k\u00f6nnen Sie jederzeit gegen diese Art der Datenverarbeitung widersprechen. Wir d\u00fcrfen Ihre Daten danach nicht mehr f\u00fcr Direktmarketing verwenden.<\/p><\/li><li><p>Werden Daten verwendet, um Profiling zu betreiben, k\u00f6nnen Sie jederzeit gegen diese Art der Datenverarbeitung widersprechen. Wir d\u00fcrfen Ihre Daten danach nicht mehr f\u00fcr Profiling verwenden.<\/p><\/li><\/ul><\/li><li><p>Sie haben laut Artikel 22 DSGVO unter Umst\u00e4nden das Recht, nicht einer ausschlie\u00dflich auf einer automatisierten Verarbeitung (zum Beispiel Profiling) beruhenden Entscheidung unterworfen zu werden.<\/p><\/li><\/ul><p>Kurz gesagt: Sie haben Rechte \u2013 z\u00f6gern Sie nicht, die oben gelistete verantwortliche Stelle bei uns zu kontaktieren!<\/p><p>Wenn Sie glauben, dass die Verarbeitung Ihrer Daten gegen das Datenschutzrecht verst\u00f6\u00dft oder Ihre datenschutzrechtlichen Anspr\u00fcche in sonst einer Weise verletzt worden sind, k\u00f6nnen Sie sich bei der Aufsichtsbeh\u00f6rde beschweren. Diese ist f\u00fcr \u00d6sterreich die Datenschutzbeh\u00f6rde, deren Website Sie unter\u00a0<a href=\"https:\/\/www.dsb.gv.at\/?tid=121888354\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.dsb.gv.at\/<\/a>\u00a0finden. In Deutschland gibt es f\u00fcr jedes Bundesland einen Datenschutzbeauftragten. F\u00fcr n\u00e4here Informationen k\u00f6nnen Sie sich an die\u00a0<a href=\"https:\/\/www.bfdi.bund.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bundesbeauftragte f\u00fcr den Datenschutz und die Informationsfreiheit (BfDI)<\/a>\u00a0wenden. F\u00fcr unser Unternehmen ist die folgende lokale Datenschutzbeh\u00f6rde zust\u00e4ndig:<\/p><p>\u00a0<\/p><h2>Webhosting<\/h2><p>Webhosting Zusammenfassung<br \/>\u00a0Betroffene: Besucher der Website<br \/>\u00a0Zweck: professionelles Hosting der Website und Absicherung des Betriebs<br \/>\u00a0Verarbeitete Daten: IP-Adresse, Zeitpunkt des Websitebesuchs, verwendeter Browser und weitere Daten. Mehr Details dazu finden Sie weiter unten bzw. beim jeweils eingesetzten Webhosting Provider.<br \/>\u00a0Speicherdauer: abh\u00e4ngig vom jeweiligen Provider, aber in der Regel 2 Wochen<br \/>\u00a0Rechtsgrundlagen: Art. 6 Abs. 1 lit.f DSGVO (Berechtigte Interessen)<\/p><p>\u00a0<\/p><h2>Was ist Webhosting?<\/h2><p>Wenn Sie heutzutage Websites besuchen, werden gewisse Informationen \u2013 auch personenbezogene Daten \u2013 automatisch erstellt und gespeichert, so auch auf dieser Website. Diese Daten sollten m\u00f6glichst sparsam und nur mit Begr\u00fcndung verarbeitet werden. Mit Website meinen wir \u00fcbrigens die Gesamtheit aller Webseiten auf einer Domain, d.h. alles von der Startseite (Homepage) bis hin zur aller letzten Unterseite (wie dieser hier). Mit Domain meinen wir zum Beispiel beispiel.de oder musterbeispiel.com.<\/p><p>Wenn Sie eine Website auf einem Bildschirm ansehen m\u00f6chten, verwenden Sie daf\u00fcr ein Programm, das sich Webbrowser nennt. Sie kennen vermutlich einige Webbrowser beim Namen: Google Chrome, Microsoft Edge, Mozilla Firefox und Apple Safari.<\/p><p>Dieser Webbrowser muss sich zu einem anderen Computer verbinden, wo der Code der Website gespeichert ist: dem Webserver. Der Betrieb eines Webservers ist eine komplizierte und aufwendige Aufgabe, weswegen dies in der Regel von professionellen Anbietern, den Providern, \u00fcbernommen wird. Diese bieten Webhosting an und sorgen damit f\u00fcr eine verl\u00e4ssliche und fehlerfreie Speicherung der Daten von Websites.<\/p><p>Bei der Verbindungsaufnahme des Browsers auf Ihrem Computer (Desktop, Laptop, Smartphone) und w\u00e4hrend der Daten\u00fcbertragung zu und vom Webserver kann es zu einer Verarbeitung personenbezogener Daten kommen. Einerseits speichert Ihr Computer Daten, andererseits muss auch der Webserver Daten eine Zeit lang speichern, um einen ordentlichen Betrieb zu gew\u00e4hrleisten.<\/p><p>Zur Veranschaulichung:<\/p><h2>Warum verarbeiten wir personenbezogene Daten?<\/h2><p>Die Zwecke der Datenverarbeitung sind:<\/p><ol><li><p>Professionelles Hosting der Website und Absicherung des Betriebs<\/p><\/li><li><p>zur Aufrechterhaltung der Betriebs- und IT-Sicherheit<\/p><\/li><li><p>Anonyme Auswertung des Zugriffsverhaltens zur Verbesserung unseres Angebots und ggf. zur Strafverfolgung bzw. Verfolgung von Anspr\u00fcchen\u00a0<\/p><\/li><\/ol><h2>Welche Daten werden verarbeitet?<\/h2><p>Auch w\u00e4hrend Sie unsere Website jetzt gerade besuchen, speichert unser Webserver, das ist der Computer auf dem diese Webseite gespeichert ist, in der Regel automatisch Daten wie<\/p><ul><li><p>die komplette Internetadresse (URL) der aufgerufenen Webseite (z. B.\u00a0<a href=\"https:\/\/www.beispielwebsite.de\/beispielunterseite.html?tid=121888354)\" target=\"_blank\" rel=\"noopener\" data-auto-recognition=\"true\">https:\/\/www.beispielwebsite.de\/beispielunterseite.html?tid=121888354)<\/a><\/p><\/li><li><p>Browser und Browserversion (z. B. Chrome 87)<\/p><\/li><li><p>das verwendete Betriebssystem (z. B. Windows 10)<\/p><\/li><li><p>die Adresse (URL) der zuvor besuchten Seite (Referrer URL) (z. B.\u00a0<a href=\"https:\/\/www.beispielquellsite.de\/vondabinichgekommen.html\/)\" target=\"_blank\" rel=\"noopener\" data-auto-recognition=\"true\">https:\/\/www.beispielquellsite.de\/vondabinichgekommen.html\/)<\/a><\/p><\/li><li><p>den Hostnamen und die IP-Adresse des Ger\u00e4ts von welchem aus zugegriffen wird (z. B. COMPUTERNAME und 194.23.43.121)<\/p><\/li><li><p>Datum und Uhrzeit<\/p><\/li><li><p>in Dateien, den sogenannten Webserver-Logfiles\u00a0<\/p><\/li><\/ul><h2>Wie lange werden Daten gespeichert?<\/h2><p>In der Regel werden die oben genannten Daten zwei Wochen gespeichert und danach automatisch gel\u00f6scht. Wir geben diese Daten nicht weiter, k\u00f6nnen jedoch nicht ausschlie\u00dfen, dass diese Daten beim Vorliegen von rechtswidrigem Verhalten von Beh\u00f6rden eingesehen werden.<\/p><p>Kurz gesagt: Ihr Besuch wird durch unseren Provider (Firma, die unsere Website auf speziellen Computern (Servern) laufen l\u00e4sst), protokolliert, aber wir geben Ihre Daten nicht ohne Zustimmung weiter!<\/p><p>\u00a0<\/p><h2>Rechtsgrundlage<\/h2><p>Die Rechtm\u00e4\u00dfigkeit der Verarbeitung personenbezogener Daten im Rahmen des Webhosting ergibt sich aus Art. 6 Abs. 1 lit. f DSGVO (Wahrung der berechtigten Interessen), denn die Nutzung von professionellem Hosting bei einem Provider ist notwendig, um das Unternehmen im Internet sicher und nutzerfreundlich pr\u00e4sentieren und Angriffe und Forderungen hieraus gegebenenfalls verfolgen zu k\u00f6nnen.<\/p><p>Zwischen uns und dem Hostingprovider besteht in der Regel ein Vertrag \u00fcber die Auftragsverarbeitung gem\u00e4\u00df Art. 28 f. DSGVO, der die Einhaltung von Datenschutz gew\u00e4hrleistet und Datensicherheit garantiert.<\/p><p>Alle Texte sind urheberrechtlich gesch\u00fctzt.<\/p><p>Quelle: Erstellt mit dem\u00a0<a href=\"https:\/\/www.adsimple.at\/datenschutz-generator\/\" target=\"_blank\" rel=\"noreferrer noopener\">Datenschutz Generator<\/a>\u00a0von AdSimple<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"elementor-element elementor-element-9b532fe e-container--row e-container\" data-id=\"9b532fe\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;fixed&quot;}\">\t\t\t\t<div class=\"elementor-element elementor-element-d1d5d56 elementor-widget elementor-widget-heading\" data-id=\"d1d5d56\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">W\u00e4hringer Str. 47\/3, 1090 Wien | turkuyilmazkaya.psychotherapie@gmail.com | <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-322b7cf e-container--row e-container\" data-id=\"322b7cf\" data-element_type=\"container\">\t\t\t\t<div class=\"elementor-element elementor-element-a0dd0c8 elementor-widget elementor-widget-heading\" data-id=\"a0dd0c8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/\">Datenschutz<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be5be65 elementor-widget elementor-widget-heading\" data-id=\"be5be65\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/impressum\/\"> | Impressum |<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\t\t<div class=\"elementor-element elementor-element-17f6fe1 elementor-widget elementor-widget-heading\" data-id=\"17f6fe1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.psyonline.at\/psychotherapeutin\/160224\">PsyOnline<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76c671b elementor-align-center elementor-absolute elementor-widget elementor-widget-button\" data-id=\"76c671b\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/soforthilfe\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Soforthilfe<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"elementor-element elementor-element-364c50c0 e-container--row e-container\" data-id=\"364c50c0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;fixed&quot;}\">\t\t<div class=\"elementor-element elementor-element-2023d671 e-container--column e-container\" data-id=\"2023d671\" data-element_type=\"container\">\t\t\t\t<div class=\"elementor-element elementor-element-2f84a6b7 menu elementor-widget elementor-widget-heading\" data-id=\"2f84a6b7\" data-element_type=\"widget\" id=\"n0\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/turkuyilmazkaya-psychotherapie.com\/\">T\u00fcrk\u00fc Yilmazkaya BA.pth.<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c1c58de menu elementor-widget elementor-widget-heading\" data-id=\"6c1c58de\" data-element_type=\"widget\" id=\"n\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/turkuyilmazkaya-psychotherapie.com\/\">Psychotherapeutin in Ausbildung unter Supervision<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"elementor-element elementor-element-5272ee69 e-container--row e-container\" data-id=\"5272ee69\" data-element_type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\">\t\t\t\t<div class=\"elementor-element elementor-element-acefaec elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"acefaec\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/turkuyilmazkaya-psychotherapie.com\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-window-close\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div>\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Datenschutz Einleitung und \u00dcberblick Wir haben diese Datenschutzerkl\u00e4rung (Fassung 26.11.2021-121888354) verfasst, um Ihnen gem\u00e4\u00df der Vorgaben der\u00a0Datenschutz-Grundverordnung (EU) 2016\/679\u00a0und anwendbaren nationalen Gesetzen zu erkl\u00e4ren, welche personenbezogenen Daten (kurz Daten) wir als Verantwortliche \u2013 und die von uns beauftragten Auftragsverarbeiter (z. B. Provider) \u2013 verarbeiten, zuk\u00fcnftig verarbeiten werden und welche rechtm\u00e4\u00dfigen M\u00f6glichkeiten Sie haben. Die verwendeten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-811","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutz - T\u00fcrk\u00fc Yilmazkaya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - T\u00fcrk\u00fc Yilmazkaya\" \/>\n<meta property=\"og:description\" content=\"Datenschutz Einleitung und \u00dcberblick Wir haben diese Datenschutzerkl\u00e4rung (Fassung 26.11.2021-121888354) verfasst, um Ihnen gem\u00e4\u00df der Vorgaben der\u00a0Datenschutz-Grundverordnung (EU) 2016\/679\u00a0und anwendbaren nationalen Gesetzen zu erkl\u00e4ren, welche personenbezogenen Daten (kurz Daten) wir als Verantwortliche \u2013 und die von uns beauftragten Auftragsverarbeiter (z. B. Provider) \u2013 verarbeiten, zuk\u00fcnftig verarbeiten werden und welche rechtm\u00e4\u00dfigen M\u00f6glichkeiten Sie haben. Die verwendeten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"T\u00fcrk\u00fc Yilmazkaya\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-29T08:42:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/\",\"url\":\"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/\",\"name\":\"Datenschutz - T\u00fcrk\u00fc Yilmazkaya\",\"isPartOf\":{\"@id\":\"https:\/\/turkuyilmazkaya-psychotherapie.com\/#website\"},\"datePublished\":\"2022-12-21T11:59:49+00:00\",\"dateModified\":\"2022-12-29T08:42:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/turkuyilmazkaya-psychotherapie.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turkuyilmazkaya-psychotherapie.com\/#website\",\"url\":\"https:\/\/turkuyilmazkaya-psychotherapie.com\/\",\"name\":\"T\u00fcrk\u00fc Yilmazkaya\",\"description\":\"Psychotherapie in Wien\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turkuyilmazkaya-psychotherapie.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz - T\u00fcrk\u00fc Yilmazkaya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/","og_locale":"en_US","og_type":"article","og_title":"Datenschutz - T\u00fcrk\u00fc Yilmazkaya","og_description":"Datenschutz Einleitung und \u00dcberblick Wir haben diese Datenschutzerkl\u00e4rung (Fassung 26.11.2021-121888354) verfasst, um Ihnen gem\u00e4\u00df der Vorgaben der\u00a0Datenschutz-Grundverordnung (EU) 2016\/679\u00a0und anwendbaren nationalen Gesetzen zu erkl\u00e4ren, welche personenbezogenen Daten (kurz Daten) wir als Verantwortliche \u2013 und die von uns beauftragten Auftragsverarbeiter (z. B. Provider) \u2013 verarbeiten, zuk\u00fcnftig verarbeiten werden und welche rechtm\u00e4\u00dfigen M\u00f6glichkeiten Sie haben. Die verwendeten [&hellip;]","og_url":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/","og_site_name":"T\u00fcrk\u00fc Yilmazkaya","article_modified_time":"2022-12-29T08:42:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/","url":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/","name":"Datenschutz - T\u00fcrk\u00fc Yilmazkaya","isPartOf":{"@id":"https:\/\/turkuyilmazkaya-psychotherapie.com\/#website"},"datePublished":"2022-12-21T11:59:49+00:00","dateModified":"2022-12-29T08:42:26+00:00","breadcrumb":{"@id":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/turkuyilmazkaya-psychotherapie.com\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/turkuyilmazkaya-psychotherapie.com\/#website","url":"https:\/\/turkuyilmazkaya-psychotherapie.com\/","name":"T\u00fcrk\u00fc Yilmazkaya","description":"Psychotherapie in Wien","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turkuyilmazkaya-psychotherapie.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/wp-json\/wp\/v2\/pages\/811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/wp-json\/wp\/v2\/comments?post=811"}],"version-history":[{"count":65,"href":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/wp-json\/wp\/v2\/pages\/811\/revisions"}],"predecessor-version":[{"id":959,"href":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/wp-json\/wp\/v2\/pages\/811\/revisions\/959"}],"wp:attachment":[{"href":"https:\/\/turkuyilmazkaya-psychotherapie.com\/index.php\/wp-json\/wp\/v2\/media?parent=811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}